{"id":593,"count":1,"description":"","link":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/","name":"Motor Antik","slug":"motor-antik","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motor Antik Arsip - Cover Mobilmu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motor Antik Arsip - Cover Mobilmu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/\" \/>\n<meta property=\"og:site_name\" content=\"Cover Mobilmu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/tag\\\/motor-antik\\\/\",\"url\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/tag\\\/motor-antik\\\/\",\"name\":\"Motor Antik Arsip - Cover Mobilmu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/tag\\\/motor-antik\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/tag\\\/motor-antik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motor Antik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/\",\"name\":\"Cover Mobilmu\",\"description\":\"Cover Mobil No-1 di Indonesia\",\"publisher\":{\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#organization\",\"name\":\"Cover Mobilmu\",\"url\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogcovermobilmu.sgp1.digitaloceanspaces.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-512-cover-mobilmu-by-gicut-smarket.png\",\"contentUrl\":\"https:\\\/\\\/blogcovermobilmu.sgp1.digitaloceanspaces.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-512-cover-mobilmu-by-gicut-smarket.png\",\"width\":512,\"height\":512,\"caption\":\"Cover Mobilmu\"},\"image\":{\"@id\":\"https:\\\/\\\/covermobilmu.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motor Antik Arsip - Cover Mobilmu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/","og_locale":"id_ID","og_type":"article","og_title":"Motor Antik Arsip - Cover Mobilmu","og_url":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/","og_site_name":"Cover Mobilmu","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/","url":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/","name":"Motor Antik Arsip - Cover Mobilmu","isPartOf":{"@id":"https:\/\/covermobilmu.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/covermobilmu.com\/blog\/tag\/motor-antik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/covermobilmu.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Motor Antik"}]},{"@type":"WebSite","@id":"https:\/\/covermobilmu.com\/blog\/#website","url":"https:\/\/covermobilmu.com\/blog\/","name":"Cover Mobilmu","description":"Cover Mobil No-1 di Indonesia","publisher":{"@id":"https:\/\/covermobilmu.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/covermobilmu.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/covermobilmu.com\/blog\/#organization","name":"Cover Mobilmu","url":"https:\/\/covermobilmu.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/covermobilmu.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blogcovermobilmu.sgp1.digitaloceanspaces.com\/blog\/wp-content\/uploads\/2024\/07\/logo-512-cover-mobilmu-by-gicut-smarket.png","contentUrl":"https:\/\/blogcovermobilmu.sgp1.digitaloceanspaces.com\/blog\/wp-content\/uploads\/2024\/07\/logo-512-cover-mobilmu-by-gicut-smarket.png","width":512,"height":512,"caption":"Cover Mobilmu"},"image":{"@id":"https:\/\/covermobilmu.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/covermobilmu.com\/blog\/wp-json\/wp\/v2\/tags\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/covermobilmu.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/covermobilmu.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/covermobilmu.com\/blog\/wp-json\/wp\/v2\/posts?tags=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}